{"id":3094,"date":"2022-02-19T00:00:00","date_gmt":"2022-02-19T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/"},"modified":"2022-02-19T00:00:00","modified_gmt":"2022-02-19T00:00:00","slug":"la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/","title":{"rendered":"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span>Fue durante la segunda jornada de la Fiesta Nacional del Trigo, que incluy&oacute; adem&aacute;s el Monitoreo de calidad, el Concurso Nacional del cereal y la entrega del programa de Buenas Pr&aacute;cticas Agropecuarias.&nbsp;<\/span><\/p>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La cadena acompa&ntilde;&oacute; la postura de C&oacute;rdoba frente a la necesidad de eliminar las retenciones al campo y ofrecer m&aacute;s previsibilidad a los productores.<\/span><\/p>\n<p><span style=\"font-size: medium;\">Se desarroll&oacute; en Leones, la&nbsp;8&deg; Mesa Nacional del Trigo, con una convocatoria de m&aacute;s de 30 entidades de toda la cadena triguera del pa&iacute;s. La organizaci&oacute;n estuvo a cargo del&nbsp;Ministerio de Agricultura y Ganader&iacute;a de la Provincia, la&nbsp;Bolsa de Cereales de C&oacute;rdoba&nbsp;y la&nbsp;Sociedad Rural&nbsp;local. Encabezaron el encuentro, el Ministro de Agricultura y Ganader&iacute;a de la provincia, Sergio Busso; el presidente de la Bolsa de Cereales de C&oacute;rdoba, Juan Carlos Mart&iacute;nez; Delfo Emilio Buchaillot y Javier Preciado Pati&ntilde;o, integrantes del Ministerio de Agricultura, Ganader&iacute;a y Pesca de la Naci&oacute;n; y el Secretario de Agricultura de C&oacute;rdoba, Marcos Blanda.<\/span><\/p>\n<p><span style=\"font-size: medium;\">Fue una de las &uacute;ltimas actividades de la&nbsp;66&deg; edici&oacute;n de la Fiesta Nacional del Trigo, de las&nbsp;49&deg; Jornadas Trigueras Nacionales&nbsp;y de la&nbsp;1&deg; Jornada Internacional de Trigo.<\/span><\/p>\n<p><span style=\"font-size: medium;\">Adem&aacute;s, el segundo d&iacute;a incluy&oacute; el Monitoreo de calidad de Trigo, el Concurso Nacional del cereal, la entrega del programa de Buenas Pr&aacute;cticas Agropecuarias del Ministerio de Agricultura y Ganader&iacute;a de C&oacute;rdoba y el cierre del escritor, periodista y analista pol&iacute;tico Jorge As&iacute;s. En cada uno de estos espacios se ofreci&oacute; un panorama completo de los principales debates y proyecciones de la cadena.<\/span><\/p>\n<p><span style=\"font-size: medium;\">Acta acuerdo<\/span><\/p>\n<p><span style=\"font-size: medium;\">Al cierre de la 8&deg; edici&oacute;n de la Mesa Triguera Nacional, se&nbsp;emiti&oacute; un comunicado&nbsp;expresando los principales ejes que se abordaron durante la reuni&oacute;n. Acuerdos y desacuerdos, posturas y necesidades se dejaron plasmados en cada punto de este documento que servir&aacute; como eje de trabajo para el a&ntilde;o en curso y las agendas a futuro. &nbsp;<\/span><\/p>\n<p><span style=\"font-size: medium;\">Los&nbsp;ejes&nbsp;apuntan a que se ofrezca previsibilidad para la producci&oacute;n y la cadena triguera; en relaci&oacute;n a esto, algunos de los&nbsp;pedidos que m&aacute;s se repitieron, fueron: eliminar los derechos de exportaci&oacute;n, evaluar el costo impositivo en cada eslab&oacute;n de la cadena, generar financiamiento y tener un programa a largo plazo con reglas de juego claras para favorecer la inversi&oacute;n y la previsibilidad.<\/span><\/p>\n<p><span style=\"font-size: medium;\">En el documento quedaron plasmados los siguientes&nbsp;puntos centrales, en los cuales coincidieron las instituciones y representantes de los sectores privados. Los cuales podemos resumir en:<\/span><\/p>\n<p><span style=\"font-size: medium;\">&bull; Comprometer la participaci&oacute;n de diversas instituciones del sector p&uacute;blico y privado.<\/span><br \/><span style=\"font-size: medium;\">&bull; Consolidar a TrigAr como marca pa&iacute;s que nos identifique como cadena y en los mercados internacionales.<\/span><br \/><span style=\"font-size: medium;\">&bull; Avanzar con propuestas legislativas que contribuyan a toda la cadena.<\/span><br \/><span style=\"font-size: medium;\">&bull; Solicitar el fortalecimiento de las instituciones de investigaci&oacute;n en relaci&oacute;n a la cadena de trigo y biotecnolog&iacute;a.<\/span><br \/><span style=\"font-size: medium;\">&bull; Trabajar en comercio internacional por miedo de la colaboraci&oacute;n p&uacute;blico-privada.<\/span><br \/><span style=\"font-size: medium;\">&bull; Fomentar acciones para disminuir el riesgo (seguros) y tener mayores herramientas de financiamiento.<\/span><br \/><span style=\"font-size: medium;\">&bull; Generar un programa de Buenas Pr&aacute;cticas Agropecuarias a nivel nacional.<\/span><br \/><span style=\"font-size: medium;\">&bull; Construir una visi&oacute;n sist&eacute;mica del trigo y lograra una comunicaci&oacute;n unificada de la cadena.<\/span><br \/><span style=\"font-size: medium;\">&bull; Promover las exportaciones y el valor agregado del trigo.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: medium;\">Aporte al Club de Leones<\/span><\/p>\n<p><span style=\"font-size: medium;\">Al cierre de todas las actividades, los ministros Busso y Massei, hicieron entrega de un aporte al Club Leones de $4.670.000, en representaci&oacute;n del Gobierno de C&oacute;rdoba, para la organizaci&oacute;n de la Fiesta Nacional del Trigo. Los acompa&ntilde;aron los legisladores Miguel &Aacute;ngel Majul y Julieta Rinaldi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\"><br \/><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.bccba.org.ar\/wp-content\/uploads\/2021\/11\/documento-de-acuerdos-sobre-politica-triguera.pdf?embtrk=8b9i-R-53810629-R-5e2dp-R-6b:al58\"><span style=\"font-size: medium;\">VER ACTA&nbsp;<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue durante la segunda jornada de la Fiesta Nacional del Trigo, que incluy&oacute; adem&aacute;s el Monitoreo de calidad, el Concurso&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-3094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"Fue durante la segunda jornada de la Fiesta Nacional del Trigo, que incluy&oacute; adem&aacute;s el Monitoreo de calidad, el Concurso...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-19T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"219\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/\",\"name\":\"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg\",\"datePublished\":\"2022-02-19T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg\",\"width\":219,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/","og_locale":"es_ES","og_type":"article","og_title":"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"Fue durante la segunda jornada de la Fiesta Nacional del Trigo, que incluy&oacute; adem&aacute;s el Monitoreo de calidad, el Concurso...","og_url":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2022-02-19T00:00:00+00:00","og_image":[{"width":219,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/","url":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/","name":"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg","datePublished":"2022-02-19T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/6210eb799ac47.jpg","width":219,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/la-8-mesa-nacional-del-trigo-dejo-propuestas-que-incluyen-a-toda-la-cadena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"La 8\u00b0 Mesa Nacional del Trigo dej\u00f3 propuestas que incluyen a toda la cadena"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=3094"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/3095"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=3094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=3094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=3094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}