{"id":3060,"date":"2022-01-06T00:00:00","date_gmt":"2022-01-06T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/"},"modified":"2022-01-06T00:00:00","modified_gmt":"2022-01-06T00:00:00","slug":"colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/","title":{"rendered":"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El ciclo 2021\/22 experiment&oacute; una expansi&oacute;n de la superficie implantada de colza del 59 %, unas 3.550 hect&aacute;reas (ha) m&aacute;s que la campa&ntilde;a anterior. El &aacute;rea sembrada fue de 9.550 ha.<\/span><\/p>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El Sistema de Informaci&oacute;n de Bolsa de Cereales de Entre R&iacute;os (SIBER) destac&oacute; que el rendimiento promedio provincial fue el m&aacute;s elevado de los &uacute;ltimos 10 a&ntilde;os. Adem&aacute;s, el mismo registr&oacute; un incremento interanual del 74 % (782 kg\/ha), mientras que, en relaci&oacute;n al promedio del &uacute;ltimo lustro el crecimiento fue del 33 % (461 kg\/ha). Con un rendimiento promedio&nbsp; de 1.840 kg\/ha, la producci&oacute;n de colza tuvo un aumento interanual del 243 % (12.445 t), ubic&aacute;ndose en 17.575 toneladas (t).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Seg&uacute;n los datos relevados del SIBER, el principal departamento productor de colza fue Victoria, ya que concentr&oacute; el 56 % del &aacute;rea implantada y el 58 % del total de las toneladas de la provincia. El segundo lugar, pero muy distante, correspondi&oacute; a Gualeguay que particip&oacute; del 15 % de la superficie cultivada y del 16 % de la producci&oacute;n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ciclo 2021\/22 experiment&oacute; una expansi&oacute;n de la superficie implantada de colza del 59 %, unas 3.550 hect&aacute;reas (ha) m&aacute;s&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-3060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"El ciclo 2021\/22 experiment&oacute; una expansi&oacute;n de la superficie implantada de colza del 59 %, unas 3.550 hect&aacute;reas (ha) m&aacute;s...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-06T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/\",\"name\":\"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg\",\"datePublished\":\"2022-01-06T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg\",\"width\":198,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"El ciclo 2021\/22 experiment&oacute; una expansi&oacute;n de la superficie implantada de colza del 59 %, unas 3.550 hect&aacute;reas (ha) m&aacute;s...","og_url":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2022-01-06T00:00:00+00:00","og_image":[{"width":198,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/","url":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/","name":"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg","datePublished":"2022-01-06T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61d6ffac8d506.jpg","width":198,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/colza-el-rinde-promedio-provincial-fue-el-mas-elevado-de-los-ultimos-10-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Colza: El rinde promedio provincial fue el m\u00e1s elevado de los \u00faltimos 10 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=3060"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/3061"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=3060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=3060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=3060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}