{"id":3036,"date":"2021-12-16T00:00:00","date_gmt":"2021-12-16T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/"},"modified":"2021-12-16T00:00:00","modified_gmt":"2021-12-16T00:00:00","slug":"las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/","title":{"rendered":"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Comunicado de las entidades empresarias de la provincia de Entre R&iacute;os.&nbsp;<\/span><\/p>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Entre R&iacute;os atraviesa un momento institucional delicado. Por primera vez en su historia, un exgobernador enfrenta un juicio oral acusado de hechos de corrupci&oacute;n. En medio del proceso, el Jurado de Enjuiciamiento decidi&oacute; abrir un Jury contra la fiscal anticorrupci&oacute;n, a cargo de la acusaci&oacute;n en esta causa de gran relevancia institucional. El Jurado de Enjuiciamiento resolvi&oacute; adem&aacute;s suspender a la fiscal en el cargo durante seis meses y apartar del proceso de enjuiciamiento al Ministerio P&uacute;blico Fiscal, que es el &oacute;rgano de acusaci&oacute;n previsto en la ley.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Las entidades que firman este comunicado ven con preocupaci&oacute;n estos acontecimientos, que transmiten un mensaje alarmante a la sociedad entrerriana acerca de la independencia del poder judicial y los riesgos de investigar causas de corrupci&oacute;n que involucran al poder pol&iacute;tico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Todas las personas deben responder ante la ley, sin privilegios ni excepciones. Esto alcanza tanto a los gobernadores como al Poder Judicial. Y, por supuesto, a la fiscal anticorrupci&oacute;n. El Jury es el mecanismo previsto en la Constituci&oacute;n Provincial para remover a jueces y fiscales que no cumplen sus funciones como corresponde, pero las decisiones de suspender a la fiscal anticorrupci&oacute;n en su cargo y apartar a todo el Ministerio P&uacute;blico Fiscal de su rol institucional resultan arbitrarias y desproporcionadas. En especial si se tiene en cuenta que el inicio del Jury est&aacute; vinculado a la causa Contratos, de la que la fiscal ya se excus&oacute; y en la que, por lo tanto, ya no tiene participaci&oacute;n ni injerencia alguna. Resulta entonces inevitable sospechar una motivaci&oacute;n pol&iacute;tica detr&aacute;s de estas decisiones.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La investigaci&oacute;n de la corrupci&oacute;n debe ser implacable y transparente. La buena salud de las instituciones republicanas depende de que la ciudadan&iacute;a conf&iacute;e en que la ley es igual para todos y no existen dispositivos corporativos para proteger a quienes detentan el poder. La suspensi&oacute;n de la fiscal y el apartamiento del Ministerio P&uacute;blico Fiscal como &oacute;rgano acusador minan la base de esa confianza y generan dudas sobre la fortaleza de las instituciones para sostener dos pilares fundamentales: evitar la impunidad y garantizar un juicio imparcial y justo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Las entidades firmantes exhortan tanto al Jurado de Enjuiciamiento como a los jueces de la causa a dar a la ciudadan&iacute;a entrerriana un mensaje claro que reafirme la fortaleza de las instituciones, la vigencia del Estado de Derecho y la igualdad ante la ley.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Entidades firmantes:<\/strong><\/p>\n<p><em>-Bolsa de Cereales de Entre R&iacute;os<\/em><\/p>\n<p><em>-Bolsa de Comercio de Entre R&iacute;os<\/em><\/p>\n<p><em>-C&aacute;mara de Comercio Exterior de Entre R&iacute;os<\/em><\/p>\n<p><em>&#8211; Colegio de Corredores P&uacute;blicos Inmobiliarios de Entre R&iacute;os<\/em><\/p>\n<p><em>-Consejo Empresario de Entre R&iacute;os<\/em><\/p>\n<p><em>-Corporaci&oacute;n para el Desarrollo de Paran&aacute;<\/em><\/p>\n<p><em>-Federaci&oacute;n Agraria Argentina Filial Entre R&iacute;os<\/em><\/p>\n<p><em>-Federaci&oacute;n de Asociaciones Rurales de Entre R&iacute;os<\/em><\/p>\n<p><em>-Federaci&oacute;n Econ&oacute;mica de Entre R&iacute;os<\/em><\/p>\n<p><em>-Federaci&oacute;n Entrerriana de Cooperativas<\/em><\/p>\n<p><em>-Sociedad Rural Argentina Distrito Entre R&iacute;os<\/em><\/p>\n<p><em>-Uni&oacute;n Industrial de Entre R&iacute;os<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicado de las entidades empresarias de la provincia de Entre R&iacute;os.&nbsp; Entre R&iacute;os atraviesa un momento institucional delicado. Por primera&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-3036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"Comunicado de las entidades empresarias de la provincia de Entre R&iacute;os.&nbsp; Entre R&iacute;os atraviesa un momento institucional delicado. Por primera...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/\",\"name\":\"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg\",\"datePublished\":\"2021-12-16T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg\",\"width\":198,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/","og_locale":"es_ES","og_type":"article","og_title":"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"Comunicado de las entidades empresarias de la provincia de Entre R&iacute;os.&nbsp; Entre R&iacute;os atraviesa un momento institucional delicado. Por primera...","og_url":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2021-12-16T00:00:00+00:00","og_image":[{"width":198,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/","url":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/","name":"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg","datePublished":"2021-12-16T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61bb40c105dd8.jpg","width":198,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/las-entidades-empresarias-de-entre-rios-en-resguardo-de-la-independencia-de-los-poderes-y-la-fortaleza-institucional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Las entidades empresarias de Entre R\u00edos, en resguardo de la independencia de los poderes y la fortaleza institucional"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=3036"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/3036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/3037"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=3036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=3036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=3036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}