{"id":2982,"date":"2021-10-27T00:00:00","date_gmt":"2021-10-27T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/"},"modified":"2021-10-27T00:00:00","modified_gmt":"2021-10-27T00:00:00","slug":"cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/","title":{"rendered":"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">A partir de datos de tecnolog&iacute;a aplicada por productores, precios y comercializaci&oacute;n aportada por la Red de Colaboradores del SIBER, se presentaron diferentes resultados seg&uacute;n las cuatro regiones de la provincia.<\/span><\/p>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La Bolsa de Cereales de Entre R&iacute;os junto al INTA EEA Paran&aacute; emitieron un nuevo reporte con informaci&oacute;n econ&oacute;mica de la pr&oacute;xima campa&ntilde;a 2021\/22 del cultivo de soja de primera.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Los resultados se presentaron para las cuatro regiones de la provincia: Norte (departamentos de Villaguay, Federal, Feliciano y La Paz), Este (departamentos de Federaci&oacute;n, Concordia, San Salvador y Col&oacute;n), Oeste (departamentos de Paran&aacute;, Diamante, Victoria y Nogoy&aacute;) y Sur (departamentos de Tala, Uruguay, Gualeguay y Gualeguaych&uacute;).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En la zona Norte, el promedio de rendimiento obtenido en el &uacute;ltimo quinquenio es de 2.160 kg\/ha, siendo el costo de implantaci&oacute;n m&aacute;s comercializaci&oacute;n de 1.040 kg\/ha; aunque cuando se incluye el arrendamiento promedio en la zona el costo se eleva a 1.600 kg\/ha.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En la zona Este, el rendimiento promedio en el &uacute;ltimo quinquenio es de 2.100 kg\/ha. Por lo que se necesitan pr&aacute;cticamente 1.600 kg\/ha para cubrir todos los gastos incluyendo el arrendamiento; mientras que, sin arrendamiento, ser&iacute;an necesarios 1.050 kg\/ha.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En la zona Oeste, con un rinde promedio en el &uacute;ltimo quinquenio de 2.370 kg\/ha, se necesitan 1.900 kg\/ha para cubrir el total de los gastos con el arrendamiento. En tanto, sin arrendamiento, el reporte arroja 1.030 kg\/ha.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En la zona Sur, los productores de esta zona necesitan unos 1.930 kg\/ha para cubrir todos los gastos, incluyendo el arrendamiento. En tanto, sin arrendar se requieren 1.050 kg\/ha. El rendimiento promedio de esta zona es de 2.240 kg\/ha en los &uacute;ltimos cinco a&ntilde;os.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Para descargar el informe completo, acceder <a href=\"..\/..\/archivos\/informe\/616eca51981ad.pdf\">aqu&iacute;<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de datos de tecnolog&iacute;a aplicada por productores, precios y comercializaci&oacute;n aportada por la Red de Colaboradores del SIBER,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-2982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"A partir de datos de tecnolog&iacute;a aplicada por productores, precios y comercializaci&oacute;n aportada por la Red de Colaboradores del SIBER,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-27T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/\",\"name\":\"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg\",\"datePublished\":\"2021-10-27T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg\",\"width\":198,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/","og_locale":"es_ES","og_type":"article","og_title":"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"A partir de datos de tecnolog&iacute;a aplicada por productores, precios y comercializaci&oacute;n aportada por la Red de Colaboradores del SIBER,...","og_url":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2021-10-27T00:00:00+00:00","og_image":[{"width":198,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/","url":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/","name":"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg","datePublished":"2021-10-27T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/61794c18d57c7.jpg","width":198,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/cuanta-soja-de-primera-debe-cosechar-un-productor-en-entre-rios-para-cubrir-los-costos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Cu\u00e1nta soja de primera debe cosechar un productor en Entre R\u00edos para cubrir los costos"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=2982"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/2983"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=2982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}