{"id":2838,"date":"2021-04-30T00:00:00","date_gmt":"2021-04-30T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/"},"modified":"2021-04-30T00:00:00","modified_gmt":"2021-04-30T00:00:00","slug":"se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/","title":{"rendered":"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En Entre R&iacute;os, se cosech&oacute; el 64 % de la superficie cultivada con sorgo, inform&oacute; el Sistema de Informaci&oacute;n de Bolsa de Cereales de Entre R&iacute;os (SIBER).<\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-size: medium;\"><br \/><\/span><\/div>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El ciclo 2020\/21 tuvo un &aacute;rea cultivada de 139.000 ha, donde el 75 % (104.000 ha) fue ocupado por tipo gran&iacute;fero. El resto de la superficie corresponde a los tipos forrajero, silero o doble prop&oacute;sito.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Actualmente, el rendimiento promedio provincial se ubica en 4.000 kg\/ha, lo cual marca una disminuci&oacute;n de 500 kg\/ha en relaci&oacute;n a lo registrado hace dos semanas. El SIBER menciona que se observa una merma del 21 % (1.094 kg\/ha) con respecto al promedio provincial del ciclo 2019\/20 y del 11 % (504 kg\/ha) en comparaci&oacute;n con el promedio del &uacute;ltimo lustro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">De modificarse el rendimiento promedio provincial y descontando la superficie cultivada con sorgo forrajero, silero y doble prop&oacute;sito, se proyecta una producci&oacute;n cercana a las 416.000 t, lo cual representar&iacute;a un crecimiento interanual del 84 % (189.840 t).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Por otro lado, el SIBER inform&oacute; que la cosecha de arroz en Entre R&iacute;os avanz&oacute; 34 puntos porcentuales en los &uacute;ltimos 15 d&iacute;as y se ubica en el 90 %, es decir 57.000 ha cosechadas sobre un total de 63.500 ha sembradas en el ciclo 2020\/21.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El informe destaca que los mayores inconvenientes se ubican en la zona de riego por pozos de agua, la cual presenta un retraso en las labores a causa de las cuantiosas precipitaciones acaecidas hace dos semanas. Este sector cuenta con un avance del 79 % y participa del 59 % del &aacute;rea cultivada.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El rendimiento promedio provincial se mantiene cercano a los 8.200 kg\/ha y por lo tanto la producci&oacute;n total provincial se ubicar&iacute;a alrededor de las 520.700 t, con un incremento interanual del 25 % (125.255 t).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">En cuanto a la calidad industrial, los colaboradores han comentado que se mantiene buena.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Entre R&iacute;os, se cosech&oacute; el 64 % de la superficie cultivada con sorgo, inform&oacute; el Sistema de Informaci&oacute;n de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-2838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"En Entre R&iacute;os, se cosech&oacute; el 64 % de la superficie cultivada con sorgo, inform&oacute; el Sistema de Informaci&oacute;n de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/\",\"name\":\"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg\",\"datePublished\":\"2021-04-30T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg\",\"width\":198,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/","og_locale":"es_ES","og_type":"article","og_title":"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"En Entre R&iacute;os, se cosech&oacute; el 64 % de la superficie cultivada con sorgo, inform&oacute; el Sistema de Informaci&oacute;n de...","og_url":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2021-04-30T00:00:00+00:00","og_image":[{"width":198,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/","url":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/","name":"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg","datePublished":"2021-04-30T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/608bfe744bd55.jpg","width":198,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/se-proyecta-una-produccion-cercana-a-las-416-000-t-de-sorgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Se proyecta una producci\u00f3n cercana a las 416.000 t de sorgo"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=2838"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/2839"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=2838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=2838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}