{"id":2794,"date":"2021-03-25T00:00:00","date_gmt":"2021-03-25T00:00:00","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/"},"modified":"2021-03-25T00:00:00","modified_gmt":"2021-03-25T00:00:00","slug":"se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/","title":{"rendered":"Se inicio la cosecha de los primeros lotes de soja de primera"},"content":{"rendered":"<p style=\" font-weight: bold;\">\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">As&iacute; lo dio a conocer la Bolsa de Cereales de Entre R&iacute;os,a trav&eacute;s de su sistema de informaci&oacute;n agr&iacute;cola (SIBER). La producci&oacute;n de soja de primera se posicionar&iacute;a alrededor de 1.248.750 t en la provincia.<\/span><\/p>\n<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La superficie implantada con soja de primera en la provincia se posicionar&iacute;a en 675.000 ha. Los colaboradores del SIBER reportan que se inici&oacute; la cosecha de los primeros lotes. Por tal motivo, se les consult&oacute; sobre la actual condici&oacute;n y perspectivas de rendimiento. Los resultados fueron los siguientes:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Muy buena 9 % (Perspectiva de rendimiento superior al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Buena 44 % (Perspectiva de rendimiento similar al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Regular 36 % (Perspectiva de rendimiento inferior al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Mala 11 % (Perspectiva de rendimiento muy por debajo del promedio del &uacute;ltimo lustro).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Seg&uacute;n el informel del SIBER, con el recientemente retorno de las precipitaciones a la regi&oacute;n gener&oacute; una leve mejor&iacute;a en la oleaginosa, lamentablemente las lluvias llegaron demasiado tarde. Se sostienen proyecciones similares a lo publicado hace 15 d&iacute;as, con un rendimiento promedio provincial para la soja de primera de 1.850 kg\/ha, lo cual indicar&iacute;a una ca&iacute;da interanual del 18 % (414 kg\/ha) y del 15 % (325 kg\/ha) en relaci&oacute;n al promedio del &uacute;ltimo lustro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La producci&oacute;n de soja de primera en el ciclo 2020\/21 se posicionar&iacute;a alrededor de 1.248.750, lo cual indicar&iacute;a una ca&iacute;da interanual del 29 % (502.145 t).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">CONDICI&Oacute;N DE LA SOJA DE SEGUNDA<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La superficie implantada con soja de segunda en la provincia se posicionar&iacute;a en 470.00 ha. Tal como comunic&oacute; hace 15 d&iacute;as el SIBER, la soja de segunda presenta el escenario m&aacute;s complejo, debido a que tuvo que atravesar una situaci&oacute;n de sequ&iacute;a con inferiores reservas h&iacute;dricas en comparaci&oacute;n a la soja de primera.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">A partir de consultas efectuadas a la red de colaboradores se determin&oacute; la condici&oacute;n general del cultivo:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Muy buena 4 % (Perspectiva de rendimiento superior al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Buena 29 % (Perspectiva de rendimiento similar al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Regular 34 % (Perspectiva de rendimiento inferior al promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">&#8211; Mala 33 % (Perspectiva de rendimiento muy por debajo del promedio del &uacute;ltimo lustro)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">El SIBER destaca que el 67 % de los lotes se ubican entre una condici&oacute;n regular a mala. Dentro de la condici&oacute;n mala se reportan hect&aacute;reas que se dan por perdidas. Las proyecciones del rendimiento esperado a nivel provincial para la soja de segunda se ubican en 1.300 kg\/ha, por lo tanto, representar&iacute;a una ca&iacute;da interanual del 23 % (381 kg\/ha) y del 29 % (534 kg\/ha) en relaci&oacute;n al promedio del &uacute;ltimo lustro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">La producci&oacute;n de soja de segunda en el ciclo 2020\/21 se posicionar&iacute;a alrededor de 680.290, lo cual indicar&iacute;a un crecimiento interanual del 6 % (41.185 t). El SIBER aclara que el incremento en las toneladas se relaciona directamente con la expansi&oacute;n del &aacute;rea (hecho asociado al aumento de la superficie que tuvo la siembra de trigo en el ciclo 2020\/21).<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As&iacute; lo dio a conocer la Bolsa de Cereales de Entre R&iacute;os,a trav&eacute;s de su sistema de informaci&oacute;n agr&iacute;cola (SIBER)&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":2795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,1],"tags":[],"class_list":["post-2794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"As&iacute; lo dio a conocer la Bolsa de Cereales de Entre R&iacute;os,a trav&eacute;s de su sistema de informaci&oacute;n agr&iacute;cola (SIBER)....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"178\" \/>\n\t<meta property=\"og:image:height\" content=\"132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminbtd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminbtd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/\",\"name\":\"Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg\",\"datePublished\":\"2021-03-25T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg\",\"width\":178,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se inicio la cosecha de los primeros lotes de soja de primera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a\",\"name\":\"adminbtd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g\",\"caption\":\"adminbtd\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/","og_locale":"es_ES","og_type":"article","og_title":"Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"As&iacute; lo dio a conocer la Bolsa de Cereales de Entre R&iacute;os,a trav&eacute;s de su sistema de informaci&oacute;n agr&iacute;cola (SIBER)....","og_url":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2021-03-25T00:00:00+00:00","og_image":[{"width":178,"height":132,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg","type":"image\/jpeg"}],"author":"adminbtd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adminbtd","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/","url":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/","name":"Se inicio la cosecha de los primeros lotes de soja de primera - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg","datePublished":"2021-03-25T00:00:00+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2024\/05\/605d0d2ac5146.jpg","width":178,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/se-inicio-la-cosecha-de-los-primeros-lotes-de-soja-de-primera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Se inicio la cosecha de los primeros lotes de soja de primera"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/10ac253befb815c64e57caa9b68c889a","name":"adminbtd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3b1cf8e5d6e1ef6c0b0b5f963947ded?s=96&d=mm&r=g","caption":"adminbtd"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/adminbtd\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=2794"}],"version-history":[{"count":0,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/2794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/2795"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=2794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=2794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=2794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}