{"id":11652,"date":"2026-05-12T09:47:10","date_gmt":"2026-05-12T12:47:10","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/?p=11652"},"modified":"2026-05-12T09:51:09","modified_gmt":"2026-05-12T12:51:09","slug":"resultados-economicos-de-la-campana-de-maiz-2025-26","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/","title":{"rendered":"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26"},"content":{"rendered":"<p>Con el cierre de la campa\u00f1a de ma\u00edz 2025\/26, el Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre R\u00edos (SIBER) realiza un an\u00e1lisis de los resultados econ\u00f3micos.<\/p>\n<p>La producci\u00f3n total de ma\u00edz fue la m\u00e1s alta registrada hasta el momento por la Bolsa de Cereales de Entre R\u00edos que contempla los \u00faltimos 26 a\u00f1os, totalizando 3.437.800 toneladas, a partir de un incremento interanual del 83%. Este r\u00e9cord productivo se desprende a partir del gran rendimiento promedio provincial observado y del m\u00e1ximo hist\u00f3rico registrado en superficie sembrada.<\/p>\n<p>Mientras las hect\u00e1reas sembradas crecieron un 86% respecto a la campa\u00f1a anterior, marcando la mayor superficie implantada desde el ciclo 2013\/14, los rindes se encontraron posicionados, en promedio, en 6.550 kilos por hect\u00e1rea, mostrando una leve disminuci\u00f3n de 150 kg\/ha en comparaci\u00f3n con el ciclo anterior, pero que sin embargo se encuentra un 34% por encima del promedio del \u00faltimo quinquenio. En la Figura 1 se muestra la evoluci\u00f3n de la superficie sembrada y el rendimiento por campa\u00f1a obtenido durante los \u00faltimos diez a\u00f1os, donde se observa una tendencia creciente en la superficie sembrada mientras que los rendimientos han sido irregulares.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11653\" src=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-1.jpg\" alt=\"\" width=\"680\" height=\"432\" srcset=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-1.jpg 812w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-1-300x191.jpg 300w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-1-768x488.jpg 768w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>Los productores de ma\u00edz invirtieron un total de 331,8 millones de d\u00f3lares (sin considerar costos de arrendamiento ni de comercializaci\u00f3n), mientras que, si tenemos en cuenta el precio pizarra Rosario del 30 de abril, el valor bruto de la producci\u00f3n alcanza los 649 millones de d\u00f3lares.<br \/>\nEs importante destacar que la cotizaci\u00f3n pizarra Rosario medida en d\u00f3lares del ma\u00edz sufri\u00f3 una importante tendencia bajista a partir de enero de este a\u00f1o, lo que gener\u00f3 que se coseche a un precio menor al estimado. Al comenzar la campa\u00f1a, el mercado de futuros mostraba una posici\u00f3n abril 2026 a 175 d\u00f3lares, mientras que transcurrido el ciclo la cotizaci\u00f3n mostr\u00f3 una tendencia alcista llegando a cotizar 198 d\u00f3lares en enero, pero a partir de all\u00ed la cotizaci\u00f3n se desplom\u00f3 paulatinamente hasta el piso de 171,5 d\u00f3lares observado durante en marzo. Luego, la cotizaci\u00f3n mostr\u00f3 un repunte nuevamente hasta terminar la campa\u00f1a posicionado en 188,7 d\u00f3lares por tonelada, un 10% mayor al precio estimado al inicio de campa\u00f1a. Adem\u00e1s, dicha cotizaci\u00f3n actual se encuentra un 4,6% por debajo de la observada al cierre de la campa\u00f1a 2024\/25.<br \/>\nPor otro lado, es importante destacar que, seg\u00fan datos de SIO Granos a fecha 30 de abril, alrededor de 1.775.000 toneladas de ma\u00edz correspondientes a la campa\u00f1a 2025\/26 ya han sido concertadas a lo largo de la campa\u00f1a, principalmente desde diciembre 2025 en adelante. Este dato muestra que cerca del 52% de la producci\u00f3n entrerriana ya se encuentra negociada.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11654\" src=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-2.jpg\" alt=\"\" width=\"708\" height=\"415\" srcset=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-2.jpg 805w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-2-300x176.jpg 300w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-2-768x450.jpg 768w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/p>\n<p>La producci\u00f3n en campo propio muestra resultados positivos en todos los departamentos, con mayor rentabilidad en las regiones oeste y norte (donde se registraron los mejores rindes). Adem\u00e1s, en el promedio provincial, este tipo de manejo gener\u00f3 beneficios de alrededor de 459 U$S\/ha. En la Figura 3 se observan los m\u00e1rgenes brutos por departamento.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11655\" src=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-3.jpg\" alt=\"\" width=\"710\" height=\"589\" srcset=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-3.jpg 793w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-3-300x249.jpg 300w, https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/05\/INFORME-LAUTI-3-768x637.jpg 768w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/><\/p>\n<p>Al considerar un pago de arrendamiento anual, los altos rendimientos presentados en las zonas Oeste (403 U$S\/ha) y Norte (332 U$S\/ha) elevan el promedio provincial, pero, sin embargo, la zona sur (que concentra el 43% de las hect\u00e1reas sembradas) presenta m\u00e1rgenes negativos de aproximadamente 25 U$S\/ha, mientras que la zona este presenta m\u00e1rgenes cercanos a 110 U$S\/ha. En el promedio provincial, la producci\u00f3n en campo arrendado promedi\u00f3 beneficios de 187 d\u00f3lares por hect\u00e1rea, constituyendo beneficios de alrededor del 17%. En la Figura 4 se observan los m\u00e1rgenes brutos por departamento.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el cierre de la campa\u00f1a de ma\u00edz 2025\/26, el Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre&#8230;<\/p>\n","protected":false},"author":9,"featured_media":9231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"Con el cierre de la campa\u00f1a de ma\u00edz 2025\/26, el Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T12:47:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T12:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aldana Riffel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aldana Riffel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/\",\"url\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/\",\"name\":\"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg\",\"datePublished\":\"2026-05-12T12:47:10+00:00\",\"dateModified\":\"2026-05-12T12:51:09+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg\",\"width\":600,\"height\":500,\"caption\":\"Figura : Cosecha de Ma\u00edz de primera, Paran\u00e1, Ing. Agr. Gabriel Schonfeld\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b\",\"name\":\"Aldana Riffel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g\",\"caption\":\"Aldana Riffel\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/ariffel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/","og_locale":"es_ES","og_type":"article","og_title":"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"Con el cierre de la campa\u00f1a de ma\u00edz 2025\/26, el Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre...","og_url":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2026-05-12T12:47:10+00:00","article_modified_time":"2026-05-12T12:51:09+00:00","og_image":[{"width":600,"height":500,"url":"https:\/\/www.bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg","type":"image\/jpeg"}],"author":"Aldana Riffel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aldana Riffel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/","url":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/","name":"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26 - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage"},"image":{"@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg","datePublished":"2026-05-12T12:47:10+00:00","dateModified":"2026-05-12T12:51:09+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b"},"breadcrumb":{"@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2025\/02\/GS.jpg","width":600,"height":500,"caption":"Figura : Cosecha de Ma\u00edz de primera, Paran\u00e1, Ing. Agr. Gabriel Schonfeld"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bolsacer.org.ar\/site\/resultados-economicos-de-la-campana-de-maiz-2025-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Resultados econ\u00f3micos de la campa\u00f1a de ma\u00edz 2025\/26"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b","name":"Aldana Riffel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g","caption":"Aldana Riffel"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/ariffel\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=11652"}],"version-history":[{"count":1,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11652\/revisions"}],"predecessor-version":[{"id":11656,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11652\/revisions\/11656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/9231"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=11652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=11652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=11652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}