{"id":11540,"date":"2026-04-17T09:53:51","date_gmt":"2026-04-17T12:53:51","guid":{"rendered":"https:\/\/bolsacer.org.ar\/site\/?p=11540"},"modified":"2026-04-17T09:53:51","modified_gmt":"2026-04-17T12:53:51","slug":"las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja","status":"publish","type":"post","link":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/","title":{"rendered":"Las abundantes precipitaciones impiden que avance la cosecha de soja"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre R\u00edos finaliz\u00f3 el procesamiento de im\u00e1genes satelitales y determin\u00f3 que el \u00e1rea total implantada con soja en la provincia para el ciclo 2025\/26 alcanz\u00f3 las 1.219.500 hect\u00e1reas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Del total, el 34% fue ocupado por la soja de primera con 416.000 hect\u00e1reas, mientras que el 66% restante perteneci\u00f3 a la soja de segunda, que con 803.500 hect\u00e1reas marc\u00f3 un m\u00e1ximo hist\u00f3rico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cuanto a las labores de cosecha, durante la primera quincena de abril, la frecuencia e intensidad de las precipitaciones dejaron muy pocos d\u00edas aptos para la recolecci\u00f3n de la oleaginosa. En este contexto, se estima que a nivel provincial se ha cosechado aproximadamente el 1% del \u00e1rea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cabe recordar que el a\u00f1o pasado, a igual fecha, el avance era similar, ubic\u00e1ndose en el 3%. En comparaci\u00f3n con el promedio de los \u00faltimos cinco a\u00f1os el valor se ubica en el 9% y, por lo tanto, se observa un retraso de 7 puntos porcentuales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otra parte, el acumulado de las lluvias registradas a partir del martes 14 de abril en gran parte del territorio superaron los 80 mm. En consecuencia, se proyecta que las labores de cosecha podr\u00edan reanudarse a comienzos de la pr\u00f3xima semana, siempre que las condiciones clim\u00e1ticas resulten favorables.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre R\u00edos finaliz\u00f3 el procesamiento de im\u00e1genes satelitales y determin\u00f3&#8230;<\/p>\n","protected":false},"author":9,"featured_media":11396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-11540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-institucional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"og:description\" content=\"El Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre R\u00edos finaliz\u00f3 el procesamiento de im\u00e1genes satelitales y determin\u00f3...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/\" \/>\n<meta property=\"og:site_name\" content=\".: BOLSA DE CEREALES DE ENTRE RIOS :.\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T12:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aldana Riffel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aldana Riffel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/\",\"name\":\"Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.\",\"isPartOf\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg\",\"datePublished\":\"2026-04-17T12:53:51+00:00\",\"author\":{\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b\"},\"breadcrumb\":{\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage\",\"url\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg\",\"contentUrl\":\"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg\",\"width\":880,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/mail.bolsacer.org.ar\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las abundantes precipitaciones impiden que avance la cosecha de soja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#website\",\"url\":\"https:\/\/mail.bolsacer.org.ar\/site\/\",\"name\":\"BOLSA DE CEREALES DE ENTRE RIOS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b\",\"name\":\"Aldana Riffel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g\",\"caption\":\"Aldana Riffel\"},\"url\":\"https:\/\/bolsacer.org.ar\/site\/author\/ariffel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/","og_locale":"es_ES","og_type":"article","og_title":"Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.","og_description":"El Sistema de Informaci\u00f3n de la Bolsa de Cereales de Entre R\u00edos finaliz\u00f3 el procesamiento de im\u00e1genes satelitales y determin\u00f3...","og_url":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/","og_site_name":".: BOLSA DE CEREALES DE ENTRE RIOS :.","article_published_time":"2026-04-17T12:53:51+00:00","og_image":[{"width":880,"height":586,"url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg","type":"image\/jpeg"}],"author":"Aldana Riffel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aldana Riffel","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/","url":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/","name":"Las abundantes precipitaciones impiden que avance la cosecha de soja - .: BOLSA DE CEREALES DE ENTRE RIOS :.","isPartOf":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage"},"image":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage"},"thumbnailUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg","datePublished":"2026-04-17T12:53:51+00:00","author":{"@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b"},"breadcrumb":{"@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#primaryimage","url":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg","contentUrl":"https:\/\/bolsacer.org.ar\/site\/wp-content\/uploads\/2026\/03\/el-rapido-avance-de-la-cosecha-record-de-soja-en-2GOJHIWDIBHWZEQPEIDHFVPYLI.jpg","width":880,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/bolsacer.org.ar\/site\/las-abundantes-precipitaciones-impiden-que-avance-la-cosecha-de-soja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mail.bolsacer.org.ar\/site\/"},{"@type":"ListItem","position":2,"name":"Las abundantes precipitaciones impiden que avance la cosecha de soja"}]},{"@type":"WebSite","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#website","url":"https:\/\/mail.bolsacer.org.ar\/site\/","name":"BOLSA DE CEREALES DE ENTRE RIOS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.bolsacer.org.ar\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/cdd277007b38ff30e481eea4234adf7b","name":"Aldana Riffel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.bolsacer.org.ar\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0246b7305b470e17cb279d91131e3422?s=96&d=mm&r=g","caption":"Aldana Riffel"},"url":"https:\/\/bolsacer.org.ar\/site\/author\/ariffel\/"}]}},"_links":{"self":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/comments?post=11540"}],"version-history":[{"count":2,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11540\/revisions"}],"predecessor-version":[{"id":11542,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/posts\/11540\/revisions\/11542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media\/11396"}],"wp:attachment":[{"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/categories?post=11540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolsacer.org.ar\/site\/wp-json\/wp\/v2\/tags?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}